{"id":3,"count":7,"description":"","link":"http:\/\/canyilmaz.com.tr\/gundelik\/category\/can-yilmaz\/can-yilmazdan-inciler","name":"Can YILMAZ'dan \u0130nciler","slug":"can-yilmazdan-inciler","taxonomy":"category","parent":5,"meta":[],"_links":{"self":[{"href":"http:\/\/canyilmaz.com.tr\/gundelik\/wp-json\/wp\/v2\/categories\/3"}],"collection":[{"href":"http:\/\/canyilmaz.com.tr\/gundelik\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/canyilmaz.com.tr\/gundelik\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/canyilmaz.com.tr\/gundelik\/wp-json\/wp\/v2\/categories\/5"}],"wp:post_type":[{"href":"http:\/\/canyilmaz.com.tr\/gundelik\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}